{"id":202,"date":"2016-02-17T05:00:05","date_gmt":"2016-02-17T05:00:05","guid":{"rendered":"http:\/\/atisa.com\/blog\/?p=202"},"modified":"2016-02-17T16:51:58","modified_gmt":"2016-02-17T16:51:58","slug":"sector-inmobiliario-en-mexico-importante-factor-economico","status":"publish","type":"post","link":"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/","title":{"rendered":"Tijuana en la mira de Inversionistas Extranjeros"},"content":{"rendered":"<p>El titular de la Secretar\u00eda de Turismo de Baja California, Oscar Escobedo, ha considerado a Baja California y sobre todo la ciudad de Tijuana, como uno de los nichos de mercado m\u00e1s importantes debido a la demanda de turismo y por la apertura de nuevos negocios que hacen\u00a0<strong>inversionistas extranjeros<\/strong>.\u00a0Este proceso se debe a las acciones que ha impulsado la secretar\u00eda para mejorar la oferta tur\u00edstica en Baja California y hacer a la regi\u00f3n m\u00e1s competitiva en el sector de negocios.<\/p>\n<p>Para este 2016 est\u00e1 en proceso nuevos proyectos de construcci\u00f3n, uno de ellos es un nuevo hotel de \u201cMarriot Fair Field Inn &amp; Suites\u201d con capacidad de 142 habitaciones y una\u00a0inversi\u00f3n de 270 millones de pesos. Estas acciones demuestran la confianza que existe entre inversionistas y la ciudad de Tijuana.<\/p>\n<p>Los 3 puntos que se destacan en Tijuana para la apertura de nuevos negocios por \u00a0<strong>inversionistas extranjeros<\/strong>\u00a0 son los siguientes:<\/p>\n<ul>\n<li>\n<h3><strong>Sector industrial: <\/strong><\/h3>\n<\/li>\n<\/ul>\n<p>Tijuana exporta productos a diversas naciones y a nivel nacional cuenta con el mayor n\u00famero de empresas manufactureras con inversi\u00f3n privada en M\u00e9xico, los <a href=\"http:\/\/atisa.com\/blog\/3-sectores-industriales-en-tijuana-con-mayor-potencial\/\">principales sectores industriales<\/a> que sobresalen en la regi\u00f3n son textil, automotriz y electr\u00f3nicos.<\/p>\n<ul>\n<li>\n<h3><strong>Ubicaci\u00f3n geogr\u00e1fica:<\/strong><\/h3>\n<\/li>\n<\/ul>\n<p>La frontera internacional en el corredor que abarca San Diego y Tijuana,\u00a0 comparten \u201cla frontera m\u00e1s cruzada en el mundo\u201d. Esto es el resultado de una regi\u00f3n binacional donde se refleja el comercio y el turismo fluyente en ambas regiones.<\/p>\n<ul>\n<li>\n<h3><strong>Seguridad en la apertura de nuevos negocios: <\/strong><\/h3>\n<\/li>\n<\/ul>\n<p>La visa es necesaria para cualquier extranjero que desea realizar actividades de negocio en M\u00e9xico, el objetivo es que inversionistas extranjeros puedan permanecer en protecci\u00f3n del gobierno al obedecer el Reglamento por la Ley General de Poblaci\u00f3n.<\/p>\n<p>Los requisitos generales son muy sencillos:<\/p>\n<ol>\n<li>Formato oficial de Solicitud de Tr\u00e1mite Migratorio.<\/li>\n<li>Copia y original de todas las p\u00e1ginas del pasaporte vigente del extranjero.<\/li>\n<li>En caso de que el interesado realice el tr\u00e1mite a trav\u00e9s de un apoderado o de un representante legal, \u00e9ste deber\u00e1 acreditar tal car\u00e1cter con poder a su favor otorgado por el extranjero, y copia de una identificaci\u00f3n oficial vigente que contenga fotograf\u00eda y firma del apoderado o representante legal, seg\u00fan corresponda.<\/li>\n<\/ol>\n<p>Para mayor informaci\u00f3n consulte la p\u00e1gina <a href=\"http:\/\/www.inm.gob.mx\/index.php\/page\/Manual_tramites\">&#8220;Tr\u00e1mites migratorios&#8221;<\/a>.<\/p>\n<p>Tijuana ocupa el tercer lugar en el pa\u00eds con mayor n\u00famero de personas\u00a0 y\u00a0 es una de las ciudades m\u00e1s pobladas e importantes en el estado de Baja California, esto la convierte en una ciudad atractiva para <strong>inversionistas extranjeros<\/strong> que desean posicionar negocios en la regi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El titular de la Secretar\u00eda de Turismo de Baja California, Oscar Escobedo, ha considerado a Baja California y sobre todo la ciudad de Tijuana, como uno de los nichos de mercado m\u00e1s importantes debido a la demanda de turismo y&hellip; <a href=\"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/\" class=\"more-link\">Continue Reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":429,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[26],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tijuana en la mira de Inversionistas Extranjeros - Atisa Industrial<\/title>\n<meta name=\"description\" content=\"El titular de la Secretar\u00eda de Turismo de Baja California, Oscar Escobedo, ha considerado a Baja California y sobre todo la ciudad de Tijuana, como uno de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tijuana en la mira de Inversionistas Extranjeros - Atisa Industrial\" \/>\n<meta property=\"og:description\" content=\"El titular de la Secretar\u00eda de Turismo de Baja California, Oscar Escobedo, ha considerado a Baja California y sobre todo la ciudad de Tijuana, como uno de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/\" \/>\n<meta property=\"og:site_name\" content=\"Atisa Industrial\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-17T05:00:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-17T16:51:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/atisa.com\/blog\/wp-content\/uploads\/2016\/02\/Tijuana-in-the-sight-of-Foreign-Investors-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Atisa Industrial\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Atisa Industrial\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/\"},\"author\":{\"name\":\"Atisa Industrial\",\"@id\":\"https:\/\/atisa.com\/blog\/#\/schema\/person\/6258afb3dd4a28e433993975c20370b4\"},\"headline\":\"Tijuana en la mira de Inversionistas Extranjeros\",\"datePublished\":\"2016-02-17T05:00:05+00:00\",\"dateModified\":\"2016-02-17T16:51:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/\"},\"wordCount\":447,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/atisa.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/atisa.com\/blog\/wp-content\/uploads\/2016\/02\/Tijuana-in-the-sight-of-Foreign-Investors-1.jpg\",\"keywords\":[\"Tijuana\"],\"articleSection\":[\"Tijuana\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/\",\"url\":\"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/\",\"name\":\"Tijuana en la mira de Inversionistas Extranjeros - Atisa Industrial\",\"isPartOf\":{\"@id\":\"https:\/\/atisa.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/atisa.com\/blog\/wp-content\/uploads\/2016\/02\/Tijuana-in-the-sight-of-Foreign-Investors-1.jpg\",\"datePublished\":\"2016-02-17T05:00:05+00:00\",\"dateModified\":\"2016-02-17T16:51:58+00:00\",\"description\":\"El titular de la Secretar\u00eda de Turismo de Baja California, Oscar Escobedo, ha considerado a Baja California y sobre todo la ciudad de Tijuana, como uno de\",\"breadcrumb\":{\"@id\":\"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/#primaryimage\",\"url\":\"https:\/\/atisa.com\/blog\/wp-content\/uploads\/2016\/02\/Tijuana-in-the-sight-of-Foreign-Investors-1.jpg\",\"contentUrl\":\"https:\/\/atisa.com\/blog\/wp-content\/uploads\/2016\/02\/Tijuana-in-the-sight-of-Foreign-Investors-1.jpg\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/atisa.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tijuana en la mira de Inversionistas Extranjeros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/atisa.com\/blog\/#website\",\"url\":\"https:\/\/atisa.com\/blog\/\",\"name\":\"Atisa Industrial\",\"description\":\"Leaders in industrial buildings and quality real estate.\",\"publisher\":{\"@id\":\"https:\/\/atisa.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/atisa.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/atisa.com\/blog\/#organization\",\"name\":\"Atisa Group\",\"url\":\"https:\/\/atisa.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/atisa.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/atisa.com\/blog\/wp-content\/uploads\/2015\/12\/Atisa-logo.png\",\"contentUrl\":\"https:\/\/atisa.com\/blog\/wp-content\/uploads\/2015\/12\/Atisa-logo.png\",\"width\":178,\"height\":46,\"caption\":\"Atisa Group\"},\"image\":{\"@id\":\"https:\/\/atisa.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/atisa.com\/blog\/#\/schema\/person\/6258afb3dd4a28e433993975c20370b4\",\"name\":\"Atisa Industrial\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/atisa.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eb58d6ca02305099ad48e04b4f789176?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eb58d6ca02305099ad48e04b4f789176?s=96&d=mm&r=g\",\"caption\":\"Atisa Industrial\"},\"url\":\"https:\/\/atisa.com\/blog\/author\/atisa_industrial\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tijuana en la mira de Inversionistas Extranjeros - Atisa Industrial","description":"El titular de la Secretar\u00eda de Turismo de Baja California, Oscar Escobedo, ha considerado a Baja California y sobre todo la ciudad de Tijuana, como uno de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/","og_locale":"en_US","og_type":"article","og_title":"Tijuana en la mira de Inversionistas Extranjeros - Atisa Industrial","og_description":"El titular de la Secretar\u00eda de Turismo de Baja California, Oscar Escobedo, ha considerado a Baja California y sobre todo la ciudad de Tijuana, como uno de","og_url":"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/","og_site_name":"Atisa Industrial","article_published_time":"2016-02-17T05:00:05+00:00","article_modified_time":"2016-02-17T16:51:58+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/atisa.com\/blog\/wp-content\/uploads\/2016\/02\/Tijuana-in-the-sight-of-Foreign-Investors-1.jpg","type":"image\/jpeg"}],"author":"Atisa Industrial","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Atisa Industrial","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/#article","isPartOf":{"@id":"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/"},"author":{"name":"Atisa Industrial","@id":"https:\/\/atisa.com\/blog\/#\/schema\/person\/6258afb3dd4a28e433993975c20370b4"},"headline":"Tijuana en la mira de Inversionistas Extranjeros","datePublished":"2016-02-17T05:00:05+00:00","dateModified":"2016-02-17T16:51:58+00:00","mainEntityOfPage":{"@id":"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/"},"wordCount":447,"commentCount":0,"publisher":{"@id":"https:\/\/atisa.com\/blog\/#organization"},"image":{"@id":"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/#primaryimage"},"thumbnailUrl":"https:\/\/atisa.com\/blog\/wp-content\/uploads\/2016\/02\/Tijuana-in-the-sight-of-Foreign-Investors-1.jpg","keywords":["Tijuana"],"articleSection":["Tijuana"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/","url":"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/","name":"Tijuana en la mira de Inversionistas Extranjeros - Atisa Industrial","isPartOf":{"@id":"https:\/\/atisa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/#primaryimage"},"image":{"@id":"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/#primaryimage"},"thumbnailUrl":"https:\/\/atisa.com\/blog\/wp-content\/uploads\/2016\/02\/Tijuana-in-the-sight-of-Foreign-Investors-1.jpg","datePublished":"2016-02-17T05:00:05+00:00","dateModified":"2016-02-17T16:51:58+00:00","description":"El titular de la Secretar\u00eda de Turismo de Baja California, Oscar Escobedo, ha considerado a Baja California y sobre todo la ciudad de Tijuana, como uno de","breadcrumb":{"@id":"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/#primaryimage","url":"https:\/\/atisa.com\/blog\/wp-content\/uploads\/2016\/02\/Tijuana-in-the-sight-of-Foreign-Investors-1.jpg","contentUrl":"https:\/\/atisa.com\/blog\/wp-content\/uploads\/2016\/02\/Tijuana-in-the-sight-of-Foreign-Investors-1.jpg","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/atisa.com\/blog\/sector-inmobiliario-en-mexico-importante-factor-economico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/atisa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Tijuana en la mira de Inversionistas Extranjeros"}]},{"@type":"WebSite","@id":"https:\/\/atisa.com\/blog\/#website","url":"https:\/\/atisa.com\/blog\/","name":"Atisa Industrial","description":"Leaders in industrial buildings and quality real estate.","publisher":{"@id":"https:\/\/atisa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/atisa.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/atisa.com\/blog\/#organization","name":"Atisa Group","url":"https:\/\/atisa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/atisa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/atisa.com\/blog\/wp-content\/uploads\/2015\/12\/Atisa-logo.png","contentUrl":"https:\/\/atisa.com\/blog\/wp-content\/uploads\/2015\/12\/Atisa-logo.png","width":178,"height":46,"caption":"Atisa Group"},"image":{"@id":"https:\/\/atisa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/atisa.com\/blog\/#\/schema\/person\/6258afb3dd4a28e433993975c20370b4","name":"Atisa Industrial","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/atisa.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/eb58d6ca02305099ad48e04b4f789176?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb58d6ca02305099ad48e04b4f789176?s=96&d=mm&r=g","caption":"Atisa Industrial"},"url":"https:\/\/atisa.com\/blog\/author\/atisa_industrial\/"}]}},"_links":{"self":[{"href":"https:\/\/atisa.com\/blog\/wp-json\/wp\/v2\/posts\/202"}],"collection":[{"href":"https:\/\/atisa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/atisa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/atisa.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/atisa.com\/blog\/wp-json\/wp\/v2\/comments?post=202"}],"version-history":[{"count":9,"href":"https:\/\/atisa.com\/blog\/wp-json\/wp\/v2\/posts\/202\/revisions"}],"predecessor-version":[{"id":405,"href":"https:\/\/atisa.com\/blog\/wp-json\/wp\/v2\/posts\/202\/revisions\/405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/atisa.com\/blog\/wp-json\/wp\/v2\/media\/429"}],"wp:attachment":[{"href":"https:\/\/atisa.com\/blog\/wp-json\/wp\/v2\/media?parent=202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/atisa.com\/blog\/wp-json\/wp\/v2\/categories?post=202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/atisa.com\/blog\/wp-json\/wp\/v2\/tags?post=202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}